{"id":2789,"date":"2026-03-07T21:24:39","date_gmt":"2026-03-07T17:54:39","guid":{"rendered":"https:\/\/aniapply.com\/fa\/?p=2789"},"modified":"2026-03-11T20:57:21","modified_gmt":"2026-03-11T17:27:21","slug":"student-food-cost-northern-cyprus","status":"publish","type":"post","link":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/","title":{"rendered":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D9%87%D8%B2%DB%8C%D9%86%D9%87_%D9%85%D8%A7%D9%87%D8%A7%D9%86%D9%87_%D8%AE%D9%88%D8%B1%D8%AF_%D9%88_%D8%AE%D9%88%D8%B1%D8%A7%DA%A9_%D8%AF%D8%A7%D9%86%D8%B4%D8%AC%D9%88%DB%8C%DB%8C_%D8%AF%D8%B1_%D9%82%D8%A8%D8%B1%D8%B3_%D8%B4%D9%85%D8%A7%D9%84%DB%8C_%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%DB%B2%DB%B0%DB%B2%DB%B6\" >\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D8%AA%D8%AE%D9%85%DB%8C%D9%86_%D8%A8%D9%88%D8%AF%D8%AC%D9%87_%D9%85%D8%A7%D9%87%D8%A7%D9%86%D9%87_%D8%A8%D8%B1_%D8%A7%D8%B3%D8%A7%D8%B3_%D8%B3%D8%A8%DA%A9_%D8%B2%D9%86%D8%AF%DA%AF%DB%8C\" >\u062a\u062e\u0645\u06cc\u0646 \u0628\u0648\u062f\u062c\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D9%82%DB%8C%D9%85%D8%AA_%D8%A8%D8%B1%D8%AE%DB%8C_%DA%A9%D8%A7%D9%84%D8%A7%D9%87%D8%A7%DB%8C_%D8%A7%D8%B3%D8%A7%D8%B3%DB%8C_%D8%AF%D8%B1_%D8%B3%D8%A7%D9%84_2026\" >\u0642\u06cc\u0645\u062a \u0628\u0631\u062e\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0627\u0633\u0627\u0633\u06cc \u062f\u0631 \u0633\u0627\u0644 2026<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D8%B3%D9%84%D9%81_%D8%AF%D8%A7%D9%86%D8%B4%DA%AF%D8%A7%D9%87%D8%9B_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%DA%AF%D8%B2%DB%8C%D9%86%D9%87_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B5%D8%B1%D9%81%D9%87%E2%80%8C%D8%AC%D9%88%DB%8C%DB%8C\" >\u0633\u0644\u0641 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_FAQ\" >\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 (FAQ)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#%D9%86%D8%AA%DB%8C%D8%AC%D9%87%E2%80%8C%DA%AF%DB%8C%D8%B1%DB%8C\" >\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h1 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%87%D8%B2%DB%8C%D9%86%D9%87_%D9%85%D8%A7%D9%87%D8%A7%D9%86%D9%87_%D8%AE%D9%88%D8%B1%D8%AF_%D9%88_%D8%AE%D9%88%D8%B1%D8%A7%DA%A9_%D8%AF%D8%A7%D9%86%D8%B4%D8%AC%D9%88%DB%8C%DB%8C_%D8%AF%D8%B1_%D9%82%D8%A8%D8%B1%D8%B3_%D8%B4%D9%85%D8%A7%D9%84%DB%8C_%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%DB%B2%DB%B0%DB%B2%DB%B6\"><\/span>\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)<span class=\"ez-toc-section-end\"><\/span><\/h1>\n\n\n\n<p>\u0628\u0639\u062f \u0627\u0632 \u0634\u0647\u0631\u06cc\u0647 \u0648 \u0627\u062c\u0627\u0631\u0647 \u062e\u0627\u0646\u0647\u060c \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u062f\u063a\u062f\u063a\u0647 \u0647\u0631 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc \u0627\u06cc\u0631\u0627\u0646\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a: \u00ab\u0628\u0631\u0627\u06cc \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u0686\u0642\u062f\u0631 \u0628\u0627\u06cc\u062f \u06a9\u0646\u0627\u0631 \u0628\u06af\u0630\u0627\u0631\u0645\u061f\u00bb \u062e\u0628\u0631 \u062e\u0648\u0628 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u062d\u0644\u06cc \u0648 \u0648\u0641\u0648\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u062f\u06cc\u062a\u0631\u0627\u0646\u0647\u200c\u0627\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0631\u0632\u0627\u0646\u200c\u062a\u0631\u06cc\u0646 \u0645\u0642\u0627\u0635\u062f \u0628\u0631\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 <strong>\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc \u062f\u0631 \u0633\u0627\u0644 2026<\/strong> \u062f\u0642\u06cc\u0642\u0627\u064b \u0686\u0642\u062f\u0631 \u0627\u0633\u062a \u0648 \u0686\u0637\u0648\u0631 \u0628\u0627\u06cc\u062f \u0622\u0646 \u0631\u0627 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0631\u062f\u061f<\/p>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0645\u0627 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0633\u0628\u062f \u062e\u0631\u06cc\u062f \u06cc\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0634\u0645\u0627 \u062f\u0631 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0648\u062f\u062c\u0647 \u0645\u0627\u0647\u0627\u0646\u0647\u200c\u062a\u0627\u0646 \u06a9\u0645\u06a9 \u06a9\u0646\u06cc\u0645. \u0628\u0631\u0627\u06cc \u062f\u0631\u06a9 \u0628\u0647\u062a\u0631 \u0645\u062e\u0627\u0631\u062c \u06a9\u0644\u060c \u062d\u062a\u0645\u0627\u064b \u0645\u0642\u0627\u0644\u0647 \u067e\u0627\u06cc\u0647 \u0645\u0627 \u06cc\u0639\u0646\u06cc <a href=\"#\">\u0647\u0632\u06cc\u0646\u0647 \u062a\u062d\u0635\u06cc\u0644 \u0648 \u0632\u0646\u062f\u06af\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0622\u067e\u062f\u06cc\u062a 2026)<\/a> \u0631\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"food-budget-2026\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%AE%D9%85%DB%8C%D9%86_%D8%A8%D9%88%D8%AF%D8%AC%D9%87_%D9%85%D8%A7%D9%87%D8%A7%D9%86%D9%87_%D8%A8%D8%B1_%D8%A7%D8%B3%D8%A7%D8%B3_%D8%B3%D8%A8%DA%A9_%D8%B2%D9%86%D8%AF%DA%AF%DB%8C\"><\/span>\u062a\u062e\u0645\u06cc\u0646 \u0628\u0648\u062f\u062c\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f <strong>\u0645\u0647\u0627\u062c\u0631\u062a \u062a\u062d\u0635\u06cc\u0644\u06cc \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc<\/strong>\u060c \u0647\u0632\u06cc\u0646\u0647 \u062e\u0648\u0631\u0627\u06a9 \u06a9\u0627\u0645\u0644\u0627\u064b \u0628\u0647 \u0639\u0627\u062f\u062a\u200c\u0647\u0627\u06cc \u0634\u0645\u0627 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f. \u062f\u0631 \u0633\u0627\u0644 2026\u060c \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0633\u0647 \u062f\u0633\u062a\u0647 \u0627\u0635\u0644\u06cc \u062a\u0642\u0633\u06cc\u0645 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0645\u062f\u0644 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc (\u0622\u0634\u067e\u0632\u06cc \u062f\u0631 \u062e\u0627\u0646\u0647 + \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc):<\/strong> \u062d\u062f\u0648\u062f 150 \u062a\u0627 250 \u062f\u0644\u0627\u0631 \u062f\u0631 \u0645\u0627\u0647.<\/li>\n\n\n\n<li><strong>\u0645\u062f\u0644 \u0645\u062a\u0648\u0633\u0637 (\u062a\u0631\u06a9\u06cc\u0628 \u0633\u0644\u0641 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0648 \u0622\u0634\u067e\u0632\u06cc):<\/strong> \u062d\u062f\u0648\u062f 250 \u062a\u0627 350 \u062f\u0644\u0627\u0631 \u062f\u0631 \u0645\u0627\u0647.<\/li>\n\n\n\n<li><strong>\u0645\u062f\u0644 \u0631\u0641\u0627\u0647\u200c\u0637\u0644\u0628 (\u0635\u0631\u0641 \u063a\u0630\u0627 \u062f\u0631 \u0631\u0633\u062a\u0648\u0631\u0627\u0646 \u0648 \u06a9\u0627\u0641\u0647):<\/strong> \u0628\u0627\u0644\u0627\u06cc 450 \u062f\u0644\u0627\u0631 \u062f\u0631 \u0645\u0627\u0647.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%82%DB%8C%D9%85%D8%AA_%D8%A8%D8%B1%D8%AE%DB%8C_%DA%A9%D8%A7%D9%84%D8%A7%D9%87%D8%A7%DB%8C_%D8%A7%D8%B3%D8%A7%D8%B3%DB%8C_%D8%AF%D8%B1_%D8%B3%D8%A7%D9%84_2026\"><\/span>\u0642\u06cc\u0645\u062a \u0628\u0631\u062e\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0627\u0633\u0627\u0633\u06cc \u062f\u0631 \u0633\u0627\u0644 2026<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\u060c \u0648\u0627\u062d\u062f \u067e\u0648\u0644 \u062e\u0631\u06cc\u062f \u0631\u0648\u0632\u0645\u0631\u0647 \u0644\u06cc\u0631 \u062a\u0631\u06a9\u06cc\u0647 (TL) \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0644\u06cc\u0633\u062a \u0642\u06cc\u0645\u062a \u0628\u0631\u062e\u06cc \u0627\u0642\u0644\u0627\u0645 \u067e\u0631\u0645\u0635\u0631\u0641 \u0622\u0648\u0631\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>\u0646\u0627\u0645 \u06a9\u0627\u0644\u0627<\/th><th>\u0645\u0642\u062f\u0627\u0631<\/th><th>\u0642\u06cc\u0645\u062a \u062a\u0642\u0631\u06cc\u0628\u06cc (\u0644\u06cc\u0631 &#8211; TL)<\/th><\/tr><\/thead><tbody><tr><td>\u0634\u06cc\u0631 \u062a\u0627\u0632\u0647<\/td><td>\u06f1 \u0644\u06cc\u062a\u0631<\/td><td>35 &#8211; 45<\/td><\/tr><tr><td>\u062a\u062e\u0645\u200c\u0645\u0631\u063a<\/td><td>\u06f3\u06f0 \u0639\u062f\u062f\u06cc<\/td><td>115 &#8211; 145<\/td><\/tr><tr><td>\u0633\u06cc\u0646\u0647 \u0645\u0631\u063a<\/td><td>\u06f1 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645<\/td><td>190 &#8211; 240<\/td><\/tr><tr><td>\u06af\u0648\u0634\u062a \u06af\u0648\u0633\u0627\u0644\u0647 \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647<\/td><td>\u06f1 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645<\/td><td>480 &#8211; 620<\/td><\/tr><tr><td>\u0628\u0631\u0646\u062c \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a<\/td><td>\u06f1 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645<\/td><td>65 &#8211; 95<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%B3%D9%84%D9%81_%D8%AF%D8%A7%D9%86%D8%B4%DA%AF%D8%A7%D9%87%D8%9B_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%DA%AF%D8%B2%DB%8C%D9%86%D9%87_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B5%D8%B1%D9%81%D9%87%E2%80%8C%D8%AC%D9%88%DB%8C%DB%8C\"><\/span>\u0633\u0644\u0641 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u062f\u0631 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062c\u0627\u0645\u0639 \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc<\/strong>\u060c \u0647\u0645\u06cc\u0634\u0647 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645 \u0627\u0632 \u0633\u0644\u0641\u200c\u0633\u0631\u0648\u06cc\u0633 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 (Table d&#8217;h\u00f4te) \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0632\u06cc\u0646\u0647 \u06cc\u06a9 \u0648\u0639\u062f\u0647 \u063a\u0630\u0627\u06cc \u06a9\u0627\u0645\u0644 (\u0634\u0627\u0645\u0644 \u0633\u0648\u067e\u060c \u063a\u0630\u0627\u06cc \u0627\u0635\u0644\u06cc\u060c \u0628\u0631\u0646\u062c\/\u067e\u0627\u0633\u062a\u0627\u060c \u0633\u0627\u0644\u0627\u062f \u0648 \u062f\u0633\u0631) \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc\u06cc \u0645\u062b\u0644 EMU \u06cc\u0627 CIU \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0627\u0646\u200c\u062a\u0631 \u0627\u0632 \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0628\u06cc\u0631\u0648\u0646 \u0627\u0633\u062a \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u0646\u06a9\u062a\u0647 \u0637\u0644\u0627\u06cc\u06cc: \u0627\u06af\u0631 \u0628\u0627 \u0647\u0645\u200c\u0627\u062a\u0627\u0642\u06cc\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u06af\u0631\u0648\u0647\u06cc \u062e\u0631\u06cc\u062f \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0634\u067e\u0632\u06cc \u0646\u0645\u0627\u06cc\u06cc\u062f\u060c <strong>\u0647\u0632\u06cc\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0631 \u0642\u0628\u0631\u0633<\/strong> \u0628\u0631\u0627\u06cc \u0647\u0631 \u0646\u0641\u0631 \u062a\u0627 \u06f3\u06f0 \u062f\u0631\u0635\u062f \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_FAQ\"><\/span>\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 (FAQ)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>\u06f1. \u0622\u06cc\u0627 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u062d\u0644\u0627\u0644 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f\u061f<\/strong><br>\u0628\u0644\u0647\u060c \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0641\u0631\u0647\u0646\u06af \u0627\u0633\u0644\u0627\u0645\u06cc \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\u060c \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u062a\u0645\u0627\u0645 \u06af\u0648\u0634\u062a\u200c\u0647\u0627 \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u067e\u0631\u0648\u062a\u0626\u06cc\u0646\u06cc \u062f\u0631 \u0633\u0648\u067e\u0631\u0645\u0627\u0631\u06a9\u062a\u200c\u0647\u0627 \u062d\u0644\u0627\u0644 \u0647\u0633\u062a\u0646\u062f.<\/p>\n\n\n\n<p><strong>\u06f2. \u0647\u0632\u06cc\u0646\u0647 \u0622\u0628 \u0622\u0634\u0627\u0645\u06cc\u062f\u0646\u06cc \u0686\u0642\u062f\u0631 \u0627\u0633\u062a\u061f<\/strong><br>\u0622\u0628 \u0644\u0648\u0644\u0647\u200c\u06a9\u0634\u06cc \u0628\u0631\u0627\u06cc \u0646\u0648\u0634\u06cc\u062f\u0646 \u0645\u0646\u0627\u0633\u0628 \u0646\u06cc\u0633\u062a. \u0647\u0632\u06cc\u0646\u0647 \u0647\u0631 \u06af\u0627\u0644\u0646 \u06f1\u06f9 \u0644\u06cc\u062a\u0631\u06cc \u0622\u0628 \u062a\u0635\u0641\u06cc\u0647 \u0634\u062f\u0647 \u062d\u062f\u0648\u062f 45 \u0644\u06cc\u0631 \u0627\u0633\u062a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AA%DB%8C%D8%AC%D9%87%E2%80%8C%DA%AF%DB%8C%D8%B1%DB%8C\"><\/span>\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u0645\u062f\u06cc\u0631\u06cc\u062a <strong>\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc<\/strong> \u06a9\u0627\u0631 \u0633\u062e\u062a\u06cc \u0646\u06cc\u0633\u062a. \u0628\u0627 \u0628\u0648\u062f\u062c\u0647\u200c\u0627\u06cc \u062d\u062f\u0648\u062f \u06f2\u06f5\u06f0 \u062a\u0627 \u06f3\u06f0\u06f0 \u062f\u0644\u0627\u0631\u060c \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0645\u062a\u0646\u0648\u0639 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0634\u0627\u0645\u0644 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062a\u0627\u0632\u0647 \u0645\u062f\u06cc\u062a\u0631\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a.<\/p>\n\n\n\n<p><a href=\"#\">\u062f\u0631\u06cc\u0627\u0641\u062a \u0644\u06cc\u0633\u062a \u0633\u0648\u067e\u0631\u0645\u0627\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0627\u0631\u0632\u0627\u0646 \u0642\u0628\u0631\u0633<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) \u0628\u0639\u062f \u0627\u0632 \u0634\u0647\u0631\u06cc\u0647 \u0648 \u0627\u062c\u0627\u0631\u0647 \u062e\u0627\u0646\u0647\u060c \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u062f\u063a\u062f\u063a\u0647 \u0647\u0631 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5,15],"tags":[558,559,554,557,553,555,552,556],"article_status":[776,770,771,774,773,772,775],"content-creation":[],"class_list":["post-2789","post","type-post","status-publish","format-standard","hentry","category-5","category-15","tag-558","tag-559","tag-554","tag-557","tag-------2026","tag-555","tag-552","tag-556","article_status-seo","article_status-featured-image","article_status-content-images","article_status-external-links","article_status-cluster-links","article_status-megapost-links","article_status-content-edit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc\" \/>\n<meta property=\"og:description\" content=\"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) \u0628\u0639\u062f \u0627\u0632 \u0634\u0647\u0631\u06cc\u0647 \u0648 \u0627\u062c\u0627\u0631\u0647 \u062e\u0627\u0646\u0647\u060c \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u062f\u063a\u062f\u063a\u0647 \u0647\u0631 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-07T17:54:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T17:27:21+00:00\" \/>\n<meta name=\"author\" content=\"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\"},\"author\":{\"name\":\"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc\",\"@id\":\"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5\"},\"headline\":\"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)\",\"datePublished\":\"2026-03-07T17:54:39+00:00\",\"dateModified\":\"2026-03-11T17:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\"},\"wordCount\":15,\"keywords\":[\"\u0628\u0648\u062f\u062c\u0647 \u0628\u0646\u062f\u06cc \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc\",\"\u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627\",\"\u0633\u0648\u067e\u0631\u0645\u0627\u0631\u06a9\u062a \u0647\u0627\u06cc \u0627\u0631\u0632\u0627\u0646 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\",\"\u0642\u06cc\u0645\u062a \u06af\u0648\u0634\u062a \u0648 \u0645\u0631\u063a \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\",\"\u0642\u06cc\u0645\u062a \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc 2026\",\"\u0645\u062e\u0627\u0631\u062c \u0632\u0646\u062f\u06af\u06cc \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633\",\"\u0647\u0632\u06cc\u0646\u0647 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\",\"\u0647\u0632\u06cc\u0646\u0647 \u0631\u0633\u062a\u0648\u0631\u0627\u0646 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\"],\"articleSection\":[\"\u062a\u062d\u0635\u06cc\u0644\",\"\u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc\"],\"inLanguage\":\"fa-IR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\",\"url\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\",\"name\":\"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc\",\"isPartOf\":{\"@id\":\"https:\/\/aniapply.com\/fa\/#website\"},\"datePublished\":\"2026-03-07T17:54:39+00:00\",\"dateModified\":\"2026-03-11T17:27:21+00:00\",\"author\":{\"@id\":\"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5\"},\"breadcrumb\":{\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/aniapply.com\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aniapply.com\/fa\/#website\",\"url\":\"https:\/\/aniapply.com\/fa\/\",\"name\":\"\u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc\",\"description\":\"\u0645\u0647\u0627\u062c\u0631\u062a \u0633\u0631\u06cc\u0639 \u0648 \u0622\u0633\u0627\u0646 \u0628\u0647 \u0622\u0644\u0645\u0627\u0646\u060c \u062a\u0631\u06a9\u06cc\u0647 \u0648 \u0642\u0628\u0631\u0633\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aniapply.com\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5\",\"name\":\"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/aniapply.com\/fa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dee9814a2eb4ee529e5667ee62f282df961ed27a56e82b0bbc1cd30352fbe26f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dee9814a2eb4ee529e5667ee62f282df961ed27a56e82b0bbc1cd30352fbe26f?s=96&d=mm&r=g\",\"caption\":\"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc\"},\"sameAs\":[\"https:\/\/aniapply.com\/fa\"],\"url\":\"https:\/\/aniapply.com\/fa\/author\/orkide\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc","og_description":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) \u0628\u0639\u062f \u0627\u0632 \u0634\u0647\u0631\u06cc\u0647 \u0648 \u0627\u062c\u0627\u0631\u0647 \u062e\u0627\u0646\u0647\u060c \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u062f\u063a\u062f\u063a\u0647 \u0647\u0631 [&hellip;]","og_url":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/","og_site_name":"\u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc","article_published_time":"2026-03-07T17:54:39+00:00","article_modified_time":"2026-03-11T17:27:21+00:00","author":"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#article","isPartOf":{"@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/"},"author":{"name":"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc","@id":"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5"},"headline":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)","datePublished":"2026-03-07T17:54:39+00:00","dateModified":"2026-03-11T17:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/"},"wordCount":15,"keywords":["\u0628\u0648\u062f\u062c\u0647 \u0628\u0646\u062f\u06cc \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc","\u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627","\u0633\u0648\u067e\u0631\u0645\u0627\u0631\u06a9\u062a \u0647\u0627\u06cc \u0627\u0631\u0632\u0627\u0646 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc","\u0642\u06cc\u0645\u062a \u06af\u0648\u0634\u062a \u0648 \u0645\u0631\u063a \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc","\u0642\u06cc\u0645\u062a \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc 2026","\u0645\u062e\u0627\u0631\u062c \u0632\u0646\u062f\u06af\u06cc \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633","\u0647\u0632\u06cc\u0646\u0647 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc","\u0647\u0632\u06cc\u0646\u0647 \u0631\u0633\u062a\u0648\u0631\u0627\u0646 \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc"],"articleSection":["\u062a\u062d\u0635\u06cc\u0644","\u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc"],"inLanguage":"fa-IR"},{"@type":"WebPage","@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/","url":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/","name":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6) - \u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc","isPartOf":{"@id":"https:\/\/aniapply.com\/fa\/#website"},"datePublished":"2026-03-07T17:54:39+00:00","dateModified":"2026-03-11T17:27:21+00:00","author":{"@id":"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5"},"breadcrumb":{"@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aniapply.com\/fa\/student-food-cost-northern-cyprus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/aniapply.com\/fa\/"},{"@type":"ListItem","position":2,"name":"\u0647\u0632\u06cc\u0646\u0647 \u0645\u0627\u0647\u0627\u0646\u0647 \u062e\u0648\u0631\u062f \u0648 \u062e\u0648\u0631\u0627\u06a9 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0642\u0628\u0631\u0633 \u0634\u0645\u0627\u0644\u06cc (\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06f2\u06f0\u06f2\u06f6)"}]},{"@type":"WebSite","@id":"https:\/\/aniapply.com\/fa\/#website","url":"https:\/\/aniapply.com\/fa\/","name":"\u0622\u0646\u06cc \u0627\u067e\u0644\u0627\u06cc","description":"\u0645\u0647\u0627\u062c\u0631\u062a \u0633\u0631\u06cc\u0639 \u0648 \u0622\u0633\u0627\u0646 \u0628\u0647 \u0622\u0644\u0645\u0627\u0646\u060c \u062a\u0631\u06a9\u06cc\u0647 \u0648 \u0642\u0628\u0631\u0633","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aniapply.com\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Person","@id":"https:\/\/aniapply.com\/fa\/#\/schema\/person\/87172e3be9fa2fdc5f4173cea6020fd5","name":"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/aniapply.com\/fa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dee9814a2eb4ee529e5667ee62f282df961ed27a56e82b0bbc1cd30352fbe26f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dee9814a2eb4ee529e5667ee62f282df961ed27a56e82b0bbc1cd30352fbe26f?s=96&d=mm&r=g","caption":"\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc"},"sameAs":["https:\/\/aniapply.com\/fa"],"url":"https:\/\/aniapply.com\/fa\/author\/orkide\/"}]}},"_links":{"self":[{"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/posts\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/comments?post=2789"}],"version-history":[{"count":1,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/posts\/2789\/revisions"}],"predecessor-version":[{"id":2790,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/posts\/2789\/revisions\/2790"}],"wp:attachment":[{"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/media?parent=2789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/categories?post=2789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/tags?post=2789"},{"taxonomy":"article_status","embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/article_status?post=2789"},{"taxonomy":"content-creation","embeddable":true,"href":"https:\/\/aniapply.com\/fa\/wp-json\/wp\/v2\/content-creation?post=2789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}